{"id":16900,"date":"2023-06-16T22:26:02","date_gmt":"2023-06-16T20:26:02","guid":{"rendered":"https:\/\/conze.com\/?p=16900"},"modified":"2023-06-21T13:38:13","modified_gmt":"2023-06-21T11:38:13","slug":"20-siegerlander-aok-firmenlauf","status":"publish","type":"post","link":"https:\/\/conze.com\/en\/company\/news\/20-aok-company-run-in-siegen\/","title":{"rendered":"20. AOK Company Run in Siegen"},"content":{"rendered":"<div class=\"ka-content\">\n<p><strong>It was again a great 20th AOK company run in Siegen on Wednesday evening.<\/strong><\/p>\n<\/div>\n<p class=\"bodytext\">For our team \"Laufzeitfehler\" (Runtime Error) it was time again to get into the running shoes! Of course, our team could not miss the company run. Despite the hot temperatures we faced the 5 kilometers across Siegen. Contrary to the name, there was nothing wrong with the running or the time. The team finished with great times between 29:04 and 59:35 minutes.<\/p>\n<div class=\"ka-content\">\n<p class=\"bodytext\">Thank you for your participation - see you next year.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Unser Team &#8222;Laufzeitfehler&#8220; beim diesj\u00e4hrigen Siegerl\u00e4nder AOK Firmenlauf.<\/p>","protected":false},"author":12,"featured_media":16902,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[10,27],"tags":[],"class_list":["post-16900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>20. Siegerl\u00e4nder AOK Firmenlauf - CONZE<\/title>\n<meta name=\"description\" content=\"Unser Team &quot;Laufzeitfehler&quot; beim diesj\u00e4hrigen Siegerl\u00e4nder AOK Firmenlauf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conze.com\/en\/company\/news\/20-aok-company-run-in-siegen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/\"},\"author\":{\"name\":\"Dennis Conze\",\"@id\":\"https:\\\/\\\/conze.com\\\/#\\\/schema\\\/person\\\/a7e7c2b6feaa5049a39391df6aca0d16\"},\"headline\":\"20. Siegerl\u00e4nder AOK Firmenlauf\",\"datePublished\":\"2023-06-16T20:26:02+00:00\",\"dateModified\":\"2023-06-21T11:38:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/\"},\"wordCount\":86,\"publisher\":{\"@id\":\"https:\\\/\\\/conze.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg\",\"articleSection\":[\"News (de)\",\"News (en)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/\",\"url\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/\",\"name\":\"20. Siegerl\u00e4nder AOK Firmenlauf - CONZE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conze.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg\",\"datePublished\":\"2023-06-16T20:26:02+00:00\",\"dateModified\":\"2023-06-21T11:38:13+00:00\",\"description\":\"Unser Team \\\"Laufzeitfehler\\\" beim diesj\u00e4hrigen Siegerl\u00e4nder AOK Firmenlauf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg\",\"contentUrl\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conze.com\\\/unternehmen\\\/news\\\/20-siegerlander-aok-firmenlauf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/conze.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"20. Siegerl\u00e4nder AOK Firmenlauf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conze.com\\\/#website\",\"url\":\"https:\\\/\\\/conze.com\\\/\",\"name\":\"CONZE\",\"description\":\"Custom Software Engineering\",\"publisher\":{\"@id\":\"https:\\\/\\\/conze.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conze.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conze.com\\\/#organization\",\"name\":\"CONZE Informatik GmbH\",\"alternateName\":\"CONZE\",\"url\":\"https:\\\/\\\/conze.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/conze.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/03-CONZE-RGB-Cyan.png\",\"contentUrl\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/03-CONZE-RGB-Cyan.png\",\"width\":3931,\"height\":644,\"caption\":\"CONZE Informatik GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/conze.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/conze.uie\",\"https:\\\/\\\/x.com\\\/conze_com\",\"https:\\\/\\\/www.instagram.com\\\/conzeinformatik\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conze-informatik-gmbh\"],\"email\":\"info@conze.com\",\"telephone\":\"+4927124009850\",\"legalName\":\"CONZE Informatik GmbH\",\"foundingDate\":\"2009-01-01\",\"vatID\":\"DE263515741\",\"duns\":\"341201081\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/conze.com\\\/#\\\/schema\\\/person\\\/a7e7c2b6feaa5049a39391df6aca0d16\",\"name\":\"Dennis Conze\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216\",\"url\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216\",\"contentUrl\":\"https:\\\/\\\/conze.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216\",\"caption\":\"Dennis Conze\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"20. Siegerl\u00e4nder AOK Firmenlauf - CONZE","description":"Unser Team \"Laufzeitfehler\" beim diesj\u00e4hrigen Siegerl\u00e4nder AOK Firmenlauf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conze.com\/en\/company\/news\/20-aok-company-run-in-siegen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#article","isPartOf":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/"},"author":{"name":"Dennis Conze","@id":"https:\/\/conze.com\/#\/schema\/person\/a7e7c2b6feaa5049a39391df6aca0d16"},"headline":"20. Siegerl\u00e4nder AOK Firmenlauf","datePublished":"2023-06-16T20:26:02+00:00","dateModified":"2023-06-21T11:38:13+00:00","mainEntityOfPage":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/"},"wordCount":86,"publisher":{"@id":"https:\/\/conze.com\/#organization"},"image":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#primaryimage"},"thumbnailUrl":"https:\/\/conze.com\/wp-content\/uploads\/2023\/06\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg","articleSection":["News (de)","News (en)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/","url":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/","name":"20. Siegerl\u00e4nder AOK Firmenlauf - CONZE","isPartOf":{"@id":"https:\/\/conze.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#primaryimage"},"image":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#primaryimage"},"thumbnailUrl":"https:\/\/conze.com\/wp-content\/uploads\/2023\/06\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg","datePublished":"2023-06-16T20:26:02+00:00","dateModified":"2023-06-21T11:38:13+00:00","description":"Unser Team \"Laufzeitfehler\" beim diesj\u00e4hrigen Siegerl\u00e4nder AOK Firmenlauf.","breadcrumb":{"@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#primaryimage","url":"https:\/\/conze.com\/wp-content\/uploads\/2023\/06\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg","contentUrl":"https:\/\/conze.com\/wp-content\/uploads\/2023\/06\/Siegen-Firmenlauf-2023-Team-Laufzeitfehler.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/conze.com\/unternehmen\/news\/20-siegerlander-aok-firmenlauf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/conze.com\/"},{"@type":"ListItem","position":2,"name":"20. Siegerl\u00e4nder AOK Firmenlauf"}]},{"@type":"WebSite","@id":"https:\/\/conze.com\/#website","url":"https:\/\/conze.com\/","name":"CONZE","description":"Custom Software Engineering","publisher":{"@id":"https:\/\/conze.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conze.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/conze.com\/#organization","name":"CONZE Informatik GmbH","alternateName":"CONZE","url":"https:\/\/conze.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conze.com\/#\/schema\/logo\/image\/","url":"https:\/\/conze.com\/wp-content\/uploads\/2021\/03\/03-CONZE-RGB-Cyan.png","contentUrl":"https:\/\/conze.com\/wp-content\/uploads\/2021\/03\/03-CONZE-RGB-Cyan.png","width":3931,"height":644,"caption":"CONZE Informatik GmbH"},"image":{"@id":"https:\/\/conze.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conze.uie","https:\/\/x.com\/conze_com","https:\/\/www.instagram.com\/conzeinformatik\/","https:\/\/www.linkedin.com\/company\/conze-informatik-gmbh"],"email":"info@conze.com","telephone":"+4927124009850","legalName":"CONZE Informatik GmbH","foundingDate":"2009-01-01","vatID":"DE263515741","duns":"341201081","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/conze.com\/#\/schema\/person\/a7e7c2b6feaa5049a39391df6aca0d16","name":"Dennis Conze","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conze.com\/wp-content\/litespeed\/avatar\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216","url":"https:\/\/conze.com\/wp-content\/litespeed\/avatar\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216","contentUrl":"https:\/\/conze.com\/wp-content\/litespeed\/avatar\/a364ec063d4a3995a34e95fedea9db5d.jpg?ver=1788280216","caption":"Dennis Conze"}}]}},"_links":{"self":[{"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/posts\/16900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/comments?post=16900"}],"version-history":[{"count":0,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/posts\/16900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/media\/16902"}],"wp:attachment":[{"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/media?parent=16900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/categories?post=16900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conze.com\/en\/wp-json\/wp\/v2\/tags?post=16900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}